{"id":18000,"count":4,"description":"","link":"https:\/\/snaplive.news\/las-vegas\/tag\/strategic-planning\/","name":"strategic planning","slug":"strategic-planning","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/snaplive.news\/las-vegas\/wp-json\/wp\/v2\/tags\/18000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snaplive.news\/las-vegas\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/snaplive.news\/las-vegas\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/snaplive.news\/las-vegas\/wp-json\/wp\/v2\/posts?tags=18000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}