{"id":2720,"count":9,"description":"","link":"https:\/\/snaplive.news\/las-vegas\/tag\/accountability-in-policing\/","name":"accountability in policing","slug":"accountability-in-policing","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/snaplive.news\/las-vegas\/wp-json\/wp\/v2\/tags\/2720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snaplive.news\/las-vegas\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/snaplive.news\/las-vegas\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/snaplive.news\/las-vegas\/wp-json\/wp\/v2\/posts?tags=2720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}